{"id":6007,"date":"2025-04-20T16:03:31","date_gmt":"2025-04-20T14:03:31","guid":{"rendered":"https:\/\/leclosdelacorniere.com\/?p=6007"},"modified":"2025-04-20T16:19:05","modified_gmt":"2025-04-20T14:19:05","slug":"rendez-vous-aux-jardins-2025","status":"publish","type":"post","link":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/","title":{"rendered":"Rendez-vous aux jardins 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6007\" class=\"elementor elementor-6007\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f565274 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"f565274\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea8f584\" data-id=\"ea8f584\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9afecbd elementor-widget elementor-widget-heading\" data-id=\"9afecbd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-family: &quot;Paper Flowers&quot;, sans-serif; font-size: 56px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; white-space-collapse: collapse;\">Rendez-Vous aux Jardins 2025<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80f5571 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"80f5571\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb0c3ea\" data-id=\"eb0c3ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f57c57 elementor-widget elementor-widget-image\" data-id=\"5f57c57\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"634\" height=\"896\" src=\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-1.jpg\" class=\"attachment-large size-large wp-image-6015\" alt=\"\" srcset=\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-1.jpg 634w, https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-1-212x300.jpg 212w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-563734bf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"563734bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e13f93c\" data-id=\"7e13f93c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d1476 elementor-widget elementor-widget-text-editor\" data-id=\"8d1476\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><audio class=\"audio-for-speech\"><\/audio><\/p><div class=\"translate-tooltip-mtz blue sm-root translate hidden_translate\"><div class=\"header-wrapper\">\u00a0<\/div><\/div><p><audio><\/audio><\/p><div><div><div><strong style=\"font-size: 14px; color: var( --e-global-color-text );\" data-start=\"177\" data-end=\"269\">Besoin d\u2019une parenth\u00e8se bucolique ? D\u2019un moment pour respirer, r\u00eaver, vous \u00e9merveiller ?<\/strong><\/div><\/div><\/div><p data-start=\"271\" data-end=\"410\">Le jardin du <strong data-start=\"284\" data-end=\"307\">Clos de la Corni\u00e8re<\/strong> vous ouvre grand ses portes \u00e0 l\u2019occasion des <strong data-start=\"353\" data-end=\"380\">Rendez-vous aux jardins<\/strong>, les <strong data-start=\"386\" data-end=\"409\">6, 7 et 8 juin 2025<\/strong>.<\/p><p data-start=\"412\" data-end=\"732\">Entre massifs fleuris, recoins ombrag\u00e9s et senteurs envo\u00fbtantes, venez (re)d\u00e9couvrir notre petit coin de paradis, bichonn\u00e9 avec passion tout au long de l\u2019ann\u00e9e. Laissez-vous porter par la promenade, suivez une visite guid\u00e9e si le c\u0153ur vous en dit, ou simplement, fl\u00e2nez \u00e0 votre rythme et profitez de la beaut\u00e9 des lieux.<\/p><p>Petit conseil : gardez votre appareil photo \u00e0 port\u00e9e de main\u2026 vous allez vouloir capturer ces instants magiques !<\/p><p data-start=\"856\" data-end=\"940\">Sourires, nature, \u00e9changes : tout est r\u00e9uni pour un moment simple et ressour\u00e7ant.<\/p><p data-start=\"942\" data-end=\"970\"><strong data-start=\"942\" data-end=\"968\">Horaires d\u2019ouverture :<\/strong><\/p><ul data-start=\"971\" data-end=\"1074\"><li data-start=\"971\" data-end=\"1006\"><p data-start=\"973\" data-end=\"1006\">Vendredi 6 juin : 10h00 \u2013 19h00<\/p><\/li><li data-start=\"1007\" data-end=\"1039\"><p data-start=\"1009\" data-end=\"1039\">Samedi 7 juin : 9h00 \u2013 19h00<\/p><\/li><li data-start=\"1040\" data-end=\"1074\"><p data-start=\"1042\" data-end=\"1074\">Dimanche 8 juin : 9h00 \u2013 19h00<\/p><\/li><\/ul><h2><strong style=\"font-size: 14px; color: var( --e-global-color-text );\" data-start=\"1080\" data-end=\"1096\">Entr\u00e9e libre<\/strong><span style=\"font-size: 14px; color: var( --e-global-color-text );\"> \u2013 mais si vous souhaitez soutenir le jardin, une petite contribution sera toujours la bienvenue !<\/span><\/h2><h2>Rendez-vous sur l&rsquo;\u00e9v\u00e9nement <br \/>Facebook pour vous inscrire !<\/h2><p><a href=\"https:\/\/fb.me\/e\/3Q6HXzjxw\" target=\"_blank\" rel=\"noopener\">\u00a0<\/a><\/p><p>Nous avons h\u00e2te de vous accueillir et de partager avec vous notre passion.<\/p><p>\u00c0 bient\u00f4t au\u00a0<a href=\"https:\/\/www.google.com\/maps\/place\/le+clos+de+la+corni%C3%A8re\/@46.02755,5.2906771,17z\/data=!3m1!4b1!4m6!3m5!1s0x478b5529bda12485:0xa01734e82949b237!8m2!3d46.0275463!4d5.293252!16s%2Fg%2F11fcr8mx26\" target=\"_blank\" rel=\"noopener\">Clos de la Corni\u00e8re<\/a>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vous avez envie d&rsquo;un break ? Envie de vous \u00e9vader et de vous entourer de verdure ?<\/p>\n<p>Alors, venez faire un tour chez nous lors des \u00ab\u00a0Rendez-vous aux jardins\u00a0\u00bb <\/p>\n<p>au Clos de la Corni\u00e8re les 2, 3 et 4 juin 2023.<\/p>\n","protected":false},"author":1,"featured_media":6013,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[77],"tags":[79,78,80],"class_list":["post-6007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenement","tag-evenement","tag-rendez-vous-aux-jardins","tag-week-end","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rendez-vous aux jardins 2025 - leclosdelacorniere.com<\/title>\n<meta name=\"description\" content=\"Cette ann\u00e9e encore, Le Clos de la Corni\u00e8re participe \u00e0 l&#039;\u00e9v\u00e9nement National : Les rendez-vous aux jardins les 31 mai - 1er juin - 2 juin 2024\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rendez-vous aux jardins 2025 - leclosdelacorniere.com\" \/>\n<meta property=\"og:description\" content=\"Cette ann\u00e9e encore, Le Clos de la Corni\u00e8re participe \u00e0 l&#039;\u00e9v\u00e9nement National : Les rendez-vous aux jardins les 31 mai - 1er juin - 2 juin 2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"leclosdelacorniere.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100091503150330\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-20T14:03:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-20T14:19:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"584\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/leclosdelacorniere.com\/#\/schema\/person\/e96df8cd23e22c063493e5901552bc8f\"},\"headline\":\"Rendez-vous aux jardins 2025\",\"datePublished\":\"2025-04-20T14:03:31+00:00\",\"dateModified\":\"2025-04-20T14:19:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/\"},\"wordCount\":196,\"publisher\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg\",\"keywords\":[\"\u00e9v\u00e9nement\",\"Rendez-vous aux jardins\",\"week-end\"],\"articleSection\":[\"\u00c9v\u00e9nement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/\",\"url\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/\",\"name\":\"Rendez-vous aux jardins 2025 - leclosdelacorniere.com\",\"isPartOf\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg\",\"datePublished\":\"2025-04-20T14:03:31+00:00\",\"dateModified\":\"2025-04-20T14:19:05+00:00\",\"description\":\"Cette ann\u00e9e encore, Le Clos de la Corni\u00e8re participe \u00e0 l'\u00e9v\u00e9nement National : Les rendez-vous aux jardins les 31 mai - 1er juin - 2 juin 2024\",\"breadcrumb\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage\",\"url\":\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg\",\"contentUrl\":\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg\",\"width\":584,\"height\":339},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/leclosdelacorniere.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rendez-vous aux jardins 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/leclosdelacorniere.com\/#website\",\"url\":\"https:\/\/leclosdelacorniere.com\/\",\"name\":\"leclosdelacorniere.com\",\"description\":\"Jardin priv\u00e9\",\"publisher\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/leclosdelacorniere.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/leclosdelacorniere.com\/#organization\",\"name\":\"le clos de la corniere\",\"url\":\"https:\/\/leclosdelacorniere.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/leclosdelacorniere.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2023\/03\/logo-final_couleur-fond-blanc.png\",\"contentUrl\":\"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2023\/03\/logo-final_couleur-fond-blanc.png\",\"width\":1406,\"height\":695,\"caption\":\"le clos de la corniere\"},\"image\":{\"@id\":\"https:\/\/leclosdelacorniere.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100091503150330\",\"https:\/\/www.instagram.com\/leclosdelacorniere\/\",\"https:\/\/www.youtube.com\/channel\/UCKbA_yiUzdWsZDlz3S1FRZA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/leclosdelacorniere.com\/#\/schema\/person\/e96df8cd23e22c063493e5901552bc8f\",\"name\":\"Admin\",\"sameAs\":[\"http:\/\/leclosdelacorniere.com\"],\"url\":\"https:\/\/leclosdelacorniere.com\/index.php\/author\/closdelacornieregmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rendez-vous aux jardins 2025 - leclosdelacorniere.com","description":"Cette ann\u00e9e encore, Le Clos de la Corni\u00e8re participe \u00e0 l'\u00e9v\u00e9nement National : Les rendez-vous aux jardins les 31 mai - 1er juin - 2 juin 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Rendez-vous aux jardins 2025 - leclosdelacorniere.com","og_description":"Cette ann\u00e9e encore, Le Clos de la Corni\u00e8re participe \u00e0 l'\u00e9v\u00e9nement National : Les rendez-vous aux jardins les 31 mai - 1er juin - 2 juin 2024","og_url":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/","og_site_name":"leclosdelacorniere.com","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100091503150330","article_published_time":"2025-04-20T14:03:31+00:00","article_modified_time":"2025-04-20T14:19:05+00:00","og_image":[{"width":584,"height":339,"url":"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#article","isPartOf":{"@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/"},"author":{"name":"Admin","@id":"https:\/\/leclosdelacorniere.com\/#\/schema\/person\/e96df8cd23e22c063493e5901552bc8f"},"headline":"Rendez-vous aux jardins 2025","datePublished":"2025-04-20T14:03:31+00:00","dateModified":"2025-04-20T14:19:05+00:00","mainEntityOfPage":{"@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/"},"wordCount":196,"publisher":{"@id":"https:\/\/leclosdelacorniere.com\/#organization"},"image":{"@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg","keywords":["\u00e9v\u00e9nement","Rendez-vous aux jardins","week-end"],"articleSection":["\u00c9v\u00e9nement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/","url":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/","name":"Rendez-vous aux jardins 2025 - leclosdelacorniere.com","isPartOf":{"@id":"https:\/\/leclosdelacorniere.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage"},"image":{"@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg","datePublished":"2025-04-20T14:03:31+00:00","dateModified":"2025-04-20T14:19:05+00:00","description":"Cette ann\u00e9e encore, Le Clos de la Corni\u00e8re participe \u00e0 l'\u00e9v\u00e9nement National : Les rendez-vous aux jardins les 31 mai - 1er juin - 2 juin 2024","breadcrumb":{"@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#primaryimage","url":"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg","contentUrl":"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2025\/04\/Affiche-rendez-vous-aux-jardins-2025-e1745157197583.jpg","width":584,"height":339},{"@type":"BreadcrumbList","@id":"https:\/\/leclosdelacorniere.com\/index.php\/2025\/04\/20\/rendez-vous-aux-jardins-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leclosdelacorniere.com\/"},{"@type":"ListItem","position":2,"name":"Rendez-vous aux jardins 2025"}]},{"@type":"WebSite","@id":"https:\/\/leclosdelacorniere.com\/#website","url":"https:\/\/leclosdelacorniere.com\/","name":"leclosdelacorniere.com","description":"Jardin priv\u00e9","publisher":{"@id":"https:\/\/leclosdelacorniere.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leclosdelacorniere.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/leclosdelacorniere.com\/#organization","name":"le clos de la corniere","url":"https:\/\/leclosdelacorniere.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/leclosdelacorniere.com\/#\/schema\/logo\/image\/","url":"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2023\/03\/logo-final_couleur-fond-blanc.png","contentUrl":"https:\/\/leclosdelacorniere.com\/wp-content\/uploads\/2023\/03\/logo-final_couleur-fond-blanc.png","width":1406,"height":695,"caption":"le clos de la corniere"},"image":{"@id":"https:\/\/leclosdelacorniere.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100091503150330","https:\/\/www.instagram.com\/leclosdelacorniere\/","https:\/\/www.youtube.com\/channel\/UCKbA_yiUzdWsZDlz3S1FRZA"]},{"@type":"Person","@id":"https:\/\/leclosdelacorniere.com\/#\/schema\/person\/e96df8cd23e22c063493e5901552bc8f","name":"Admin","sameAs":["http:\/\/leclosdelacorniere.com"],"url":"https:\/\/leclosdelacorniere.com\/index.php\/author\/closdelacornieregmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/posts\/6007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/comments?post=6007"}],"version-history":[{"count":6,"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/posts\/6007\/revisions"}],"predecessor-version":[{"id":6024,"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/posts\/6007\/revisions\/6024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/media\/6013"}],"wp:attachment":[{"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/media?parent=6007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/categories?post=6007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leclosdelacorniere.com\/index.php\/wp-json\/wp\/v2\/tags?post=6007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}